{"id":2439,"date":"2022-05-15T16:57:20","date_gmt":"2022-05-15T14:57:20","guid":{"rendered":"https:\/\/consorziopietrapiasentina.it?portfolio=sede-della-comunita-montana-san-pietro-al-natisone"},"modified":"2022-05-15T16:57:20","modified_gmt":"2022-05-15T14:57:20","slug":"sede-della-comunita-montana-san-pietro-al-natisone","status":"publish","type":"portfolio","link":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/","title":{"rendered":"Sede della Comunit\u00e0 Montana &#8211; San Pietro al Natisone"},"content":{"rendered":"\n<h3 class=\"has-text-align-center wp-block-heading\">Sede della Comunit\u00e0 Montana<\/h3>\n\n\n<div class=\"wp-block-visual-portfolio\">\n<div class=\"vp-portfolio vp-uid-d79d7019 vp-id-1MMtqq\"\n\tdata-vp-layout=\"justified\" data-vp-content-source=\"images\" data-vp-items-style=\"fade\" data-vp-items-click-action=\"url\" data-vp-items-gap=\"12\" data-vp-items-gap-vertical=\"\" data-vp-pagination=\"load-more\" data-vp-next-page-url=\"\" data-vp-justified-row-height=\"271\" data-vp-justified-row-height-tolerance=\"0.25\" data-vp-justified-max-rows-count=\"0\" data-vp-justified-last-row=\"left\" >\n\t<div class=\"vp-portfolio__preloader-wrap\">\n\t\t<div class=\"vp-portfolio__preloader\">\n\t\t\t<img decoding=\"async\" loading=\"eager\" src=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg\" alt=\"Visual Portfolio, Posts &amp; Image Gallery for WordPress\" width=\"20\" height=\"20\" data-skip-lazy>\n\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"vp-portfolio__items-wrap\">\n\t\t\t\n<div class=\"vp-portfolio__items vp-portfolio__items-style-fade vp-portfolio__items-show-overlay-hover\">\n\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-5d326b68\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg\"\n\t\taria-label=\"Sede-della-Comunita-Montana\" \t>\n\t\n\t\t<img decoding=\"async\" width=\"1417\" height=\"1417\" src=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg\" class=\"wp-image-2302\" alt=\"\" srcset=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg 1417w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-300x300.jpg 300w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-1024x1024.jpg 1024w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-150x150.jpg 150w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-768x768.jpg 768w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-500x500.jpg 500w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-800x800.jpg 800w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-1280x1280.jpg 1280w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-370x370.jpg 370w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-90x90.jpg 90w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana-760x760.jpg 760w\" sizes=\"(max-width: 1417px) 100vw, 1417px\" \/>\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<div class=\"vp-portfolio__item-overlay\">\n\t\t\t<a\n\t\thref=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Sede-della-Comunita-Montana\" \t>\n\t\t\t<\/a>\t<\/div>\n\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-1755724e\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1.jpg\"\n\t\taria-label=\"Sede-della-Comunita-Montana1\" \t>\n\t\n\t\t<img decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1.jpg\" class=\"wp-image-2303\" alt=\"\" srcset=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1.jpg 1200w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-300x300.jpg 300w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-1024x1024.jpg 1024w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-150x150.jpg 150w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-768x768.jpg 768w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-500x500.jpg 500w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-800x800.jpg 800w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-1280x1280.jpg 1280w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-370x370.jpg 370w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-90x90.jpg 90w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1-760x760.jpg 760w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<div class=\"vp-portfolio__item-overlay\">\n\t\t\t<a\n\t\thref=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana1.jpg\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Sede-della-Comunita-Montana1\" \t>\n\t\t\t<\/a>\t<\/div>\n\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div\t\tclass=\"vp-portfolio__item-wrap vp-portfolio__item-uid-ce919d3d\" data-vp-filter=\"\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2.jpg\"\n\t\taria-label=\"Sede-della-Comunita-Montana2\" \t>\n\t\n\t\t<img decoding=\"async\" width=\"1417\" height=\"1417\" src=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2.jpg\" class=\"wp-image-2304\" alt=\"\" srcset=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2.jpg 1417w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-300x300.jpg 300w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-1024x1024.jpg 1024w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-150x150.jpg 150w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-768x768.jpg 768w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-500x500.jpg 500w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-800x800.jpg 800w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-1280x1280.jpg 1280w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-370x370.jpg 370w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-90x90.jpg 90w, https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2-760x760.jpg 760w\" sizes=\"(max-width: 1417px) 100vw, 1417px\" \/>\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<div class=\"vp-portfolio__item-overlay\">\n\t\t\t<a\n\t\thref=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/05\/Sede-della-Comunita-Montana2.jpg\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Sede-della-Comunita-Montana2\" \t>\n\t\t\t<\/a>\t<\/div>\n\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\t\t<\/div>\n\t\t\n<\/div>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sede della Comunit\u00e0 Montana &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":2440,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_vp_format_video_url":"","_vp_image_focal_point":{"x":0.45,"y":0.61},"footnotes":""},"portfolio_category":[80],"portfolio_tag":[],"class_list":["post-2439","portfolio","type-portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-realizzazioni-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sede della Comunit\u00e0 Montana - San Pietro al Natisone - Consorzio Produttori Pietra Piasentina srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sede della Comunit\u00e0 Montana - San Pietro al Natisone - Consorzio Produttori Pietra Piasentina srl\" \/>\n<meta property=\"og:description\" content=\"Sede della Comunit\u00e0 Montana &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio Produttori Pietra Piasentina srl\" \/>\n<meta property=\"og:image\" content=\"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1417\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/portfolio\\\/sede-della-comunita-montana-san-pietro-al-natisone\\\/\",\"url\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/portfolio\\\/sede-della-comunita-montana-san-pietro-al-natisone\\\/\",\"name\":\"Sede della Comunit\u00e0 Montana - San Pietro al Natisone - Consorzio Produttori Pietra Piasentina srl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/portfolio\\\/sede-della-comunita-montana-san-pietro-al-natisone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/portfolio\\\/sede-della-comunita-montana-san-pietro-al-natisone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Sede-della-Comunita-Montana.jpg\",\"datePublished\":\"2022-05-15T14:57:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/portfolio\\\/sede-della-comunita-montana-san-pietro-al-natisone\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/portfolio\\\/sede-della-comunita-montana-san-pietro-al-natisone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/portfolio\\\/sede-della-comunita-montana-san-pietro-al-natisone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Sede-della-Comunita-Montana.jpg\",\"contentUrl\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Sede-della-Comunita-Montana.jpg\",\"width\":1417,\"height\":1417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/portfolio\\\/sede-della-comunita-montana-san-pietro-al-natisone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Realizzazioni\",\"item\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/realizzazioni\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sede della Comunit\u00e0 Montana &#8211; San Pietro al Natisone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/#website\",\"url\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/\",\"name\":\"Consorzio Produttori Pietra Piasentina srl\",\"description\":\"Pietra Piasentina Torreano\",\"publisher\":{\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/#organization\",\"name\":\"Consorzio Produttori Pietra Piasentina S.r.l.\",\"url\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo1.svg\",\"contentUrl\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo1.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Consorzio Produttori Pietra Piasentina S.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/consorziopietrapiasentina.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/consorzio-pietra-piasentina-torreano-2994671b1\\\/?original_referer=httpsconsorziopietrapiasentina.it\",\"https:\\\/\\\/www.instagram.com\\\/consorzio_pietra.piasentina\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sede della Comunit\u00e0 Montana - San Pietro al Natisone - Consorzio Produttori Pietra Piasentina srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/","og_locale":"en_US","og_type":"article","og_title":"Sede della Comunit\u00e0 Montana - San Pietro al Natisone - Consorzio Produttori Pietra Piasentina srl","og_description":"Sede della Comunit\u00e0 Montana &nbsp;","og_url":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/","og_site_name":"Consorzio Produttori Pietra Piasentina srl","og_image":[{"width":1417,"height":1417,"url":"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/","url":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/","name":"Sede della Comunit\u00e0 Montana - San Pietro al Natisone - Consorzio Produttori Pietra Piasentina srl","isPartOf":{"@id":"https:\/\/consorziopietrapiasentina.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/#primaryimage"},"image":{"@id":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/#primaryimage"},"thumbnailUrl":"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg","datePublished":"2022-05-15T14:57:20+00:00","breadcrumb":{"@id":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/#primaryimage","url":"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg","contentUrl":"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/01\/Sede-della-Comunita-Montana.jpg","width":1417,"height":1417},{"@type":"BreadcrumbList","@id":"https:\/\/consorziopietrapiasentina.it\/en\/portfolio\/sede-della-comunita-montana-san-pietro-al-natisone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/consorziopietrapiasentina.it\/en\/"},{"@type":"ListItem","position":2,"name":"Realizzazioni","item":"https:\/\/consorziopietrapiasentina.it\/realizzazioni\/"},{"@type":"ListItem","position":3,"name":"Sede della Comunit\u00e0 Montana &#8211; San Pietro al Natisone"}]},{"@type":"WebSite","@id":"https:\/\/consorziopietrapiasentina.it\/#website","url":"https:\/\/consorziopietrapiasentina.it\/","name":"Consorzio Produttori Pietra Piasentina srl","description":"Pietra Piasentina Torreano","publisher":{"@id":"https:\/\/consorziopietrapiasentina.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/consorziopietrapiasentina.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/consorziopietrapiasentina.it\/#organization","name":"Consorzio Produttori Pietra Piasentina S.r.l.","url":"https:\/\/consorziopietrapiasentina.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/consorziopietrapiasentina.it\/#\/schema\/logo\/image\/","url":"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/02\/logo1.svg","contentUrl":"https:\/\/consorziopietrapiasentina.it\/wp-content\/uploads\/2022\/02\/logo1.svg","width":"1024","height":"1024","caption":"Consorzio Produttori Pietra Piasentina S.r.l."},"image":{"@id":"https:\/\/consorziopietrapiasentina.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/consorzio-pietra-piasentina-torreano-2994671b1\/?original_referer=httpsconsorziopietrapiasentina.it","https:\/\/www.instagram.com\/consorzio_pietra.piasentina\/"]}]}},"_links":{"self":[{"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/portfolio\/2439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/comments?post=2439"}],"version-history":[{"count":0,"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/portfolio\/2439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/media\/2440"}],"wp:attachment":[{"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/media?parent=2439"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/portfolio_category?post=2439"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/consorziopietrapiasentina.it\/en\/wp-json\/wp\/v2\/portfolio_tag?post=2439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}